{"id":180,"date":"2015-03-24T16:37:29","date_gmt":"2015-03-24T16:37:29","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=180"},"modified":"2015-03-24T17:07:58","modified_gmt":"2015-03-24T17:07:58","slug":"la-trivialidad-del-absoluto","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/03\/24\/la-trivialidad-del-absoluto\/","title":{"rendered":"La trivialidad del absoluto"},"content":{"rendered":"<p>Cuando Jos\u00e9 Mar\u00eda Ridao empez\u00f3 a escribir en este peri\u00f3dico (EL PA\u00cdS) con regularidad, en torno a 2001, hab\u00eda comenzado ya a publicar algunos libros, y cuando dej\u00f3 de escribir en \u00e9l, hace ahora algo m\u00e1s de dos a\u00f1os, sigui\u00f3 public\u00e1ndolos con la misma cadencia pac\u00edfica pero ind\u00f3cil. Su valiosa obra quiz\u00e1 ha quedado eclipsada o desatendida por el periodismo y el an\u00e1lisis pol\u00edtico, y sin embargo encarna una de las trayectorias m\u00e1s beligerantes y jugosas: no ha callado su inquietud ante la fabulaci\u00f3n interesada sobre el retorno al pasado, dispuesto a desmentirla sin apa\u00f1os, como hizo al menos en<em> Contra la historia<\/em> (de 2000, revisado en 2009), pero ha sido tambi\u00e9n narrador genuino a partir de su biograf\u00eda como diplom\u00e1tico en diversos destinos, entre ellos Angola, la Unesco o, como ahora, Par\u00eds, por ejemplo en El pasajero de Montauban.<\/p>\n<p>Ha sido sobre todo original int\u00e9rprete de algunos de los avatares contempor\u00e1neos de un humanismo a menudo de estirpe erasmian y heredero del mejor legado de la raz\u00f3n ilustrada, desde La paz sin excusa y Weimar entre nosotros, ambos en 2004, hasta <em>La estrategia del malestar<\/em> (2014). De ah\u00ed que algunos de sus mejores libros no tengan atadura a raz\u00f3n pol\u00edtica alguna, como su Elogio de la imperfecci\u00f3n (2006) \u2014que era una reflexi\u00f3n sobre las po\u00e9ticas de la modernidad antes de la modernidad\u2014 o incluso los retratos poderosos de Radicales libres (2011) o el que dirimi\u00f3 el diferente papel que Ortega y Aza\u00f1a escogieron para discutir la estructura del Estado a partir del Estatuto catal\u00e1n en 1932, Dos visiones de Espa\u00f1a. Quiz\u00e1 su inequ\u00edvoca y justificada proximidad a Manuel Aza\u00f1a explica adicionalmente la tirria justificad\u00edsima por el Ortega de Espa\u00f1a invertebrada, tal como la ha expuesto en varios lugares y en alg\u00fan art\u00edculo en este peri\u00f3dico definitivamente contundente. Para quien haya seguido sus libros, por tanto, este \u00faltimo contiene un giro filos\u00f3fico que escapa a la ruta hist\u00f3rica y hasta geogr\u00e1fica y viajera que hab\u00eda escogido en los anteriores. Y aun m\u00e1s, este se emplaza fuera de la tensi\u00f3n de la actualidad y la pol\u00edtica. Jos\u00e9 Mar\u00eda Ridao ha elegido el ensimismamiento reflexivo que lo acerca, parad\u00f3jicamente, a la intenci\u00f3n de sus novelas y lo aleja de sus mejores ensayos de cr\u00edtica cultural e hist\u00f3rica porque en el fondo articula y condensa el sustrato del que nacen unos y otros. \u00bfSorpresa o perplejidad? En absoluto: madurez y plenitud ensay\u00edstica de alguien que ofrece hoy, con una muy intencionada rotulaci\u00f3n, una defensa luminosa de la filosof\u00eda accidental, el subsuelo filos\u00f3fico y moral que explica un modo de abordar no s\u00f3lo la cr\u00edtica de la cultura y su condena irrefutable del relato oficial, cat\u00f3lico, nacional-cat\u00f3lico y neocat\u00f3lico del pasado espa\u00f1ol, sino la defensa abierta de los fundamentos conceptuales y morales que explican su mejor raz\u00f3n secreta: una impecable inteligencia laica, anal\u00edtica, competente y, ay, parad\u00f3jicamente orteguiana.<\/p>\n<p>Pero no orteguiana por la v\u00eda de la interpretaci\u00f3n de la historia espa\u00f1ola, sino por la v\u00eda propiamente filos\u00f3fica del escritor, aquella que cuaja en La idea de Leibniz, hacia 1947, y aquella que asoma sin desarrollar desde 1914 y sus Meditaciones del Quijote. Para sorpresa incluso m\u00eda, no s\u00e9 si del propio Jos\u00e9 Mar\u00eda Ridao, en Ortega laten algunas de las virtudes mayores que iluminan este ensayo de filosof\u00eda contra lo Absoluto, contra la nostalgia de lo Absoluto y, aun mejor, contra la tentaci\u00f3n consoladora y falseadora de aspirar o fabular Absoluto alguno. Y lo hace Ridao en dos fases complementarias: una conceptual y te\u00f3rica, y otra hist\u00f3rica, de discusi\u00f3n con otros, y entre ellos est\u00e1n S\u00f3crates o Rousseau, pero tambi\u00e9n Marx o Freud, que es el \u00faltimo, aunque ese papel muy bien hubiese podido hacerlo la madurez filos\u00f3fica de Ortega.<\/p>\n<p>Mi mayor reparo al libro, por tanto, es una nimiedad y est\u00e1 en lugar tan tonto como el subt\u00edtulo. Este volumen no re\u00fane diversos \u201censayos sobre el hombre y el Absoluto\u201d, sino que despliega un solo \u201cEnsayo\u201d. Su tema es la condici\u00f3n ilustrada, emp\u00edrica y racionalista del hombre, al\u00e9rgico a la mentira o el delirio de un Absoluto que absuelve de la responsabilidad viscosa y fr\u00e1gil de entenderse como sujeto humano: \u201cLas coartadas que proporciona el Absoluto son siempre inseguras y provisionales\u201d, y, precisamente porque lo son, \u201cno justifican actos irreparables, actos a los que el hombre se encadena comprometiendo su libertad\u201d.<\/p>\n<p>Filosof\u00eda accidental. Ensayos sobre el hombre y el Absoluto. Jos\u00e9 Mar\u00eda Ridao. Galaxia Gutenberg. Barcelona, 2015. 268 p\u00e1ginas.<\/p>\n<blockquote><p>Noticia tomada del diario: www.elpais.com (Cultura)<\/p>\n<p>Fecha: 23 de marzo, 2015<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Cuando Jos\u00e9 Mar\u00eda Ridao empez\u00f3 a escribir en este peri\u00f3dico (EL PA\u00cdS) con regularidad, en torno a 2001, hab\u00eda comenzado ya a publicar algunos libros, y cuando dej\u00f3 de escribir en \u00e9l, hace ahora algo m\u00e1s de dos a\u00f1os, sigui\u00f3 public\u00e1ndolos con la misma cadencia pac\u00edfica pero ind\u00f3cil. Su valiosa obra quiz\u00e1 ha quedado eclipsada [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,3,6],"tags":[38,40,39],"class_list":["post-180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-noticias","category-recensiones-criticas-y-analisis-de-publicaciones","tag-critica-cultural","tag-ensayo","tag-filosofia-contemporanea"],"jetpack_featured_media_url":"https:\/\/redfilosofia.es\/atheneblog\/wp-content\/uploads\/sites\/5\/2015\/03\/mex-acentos-4.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-2U","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=180"}],"version-history":[{"count":1,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/180\/revisions"}],"predecessor-version":[{"id":182,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/180\/revisions\/182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media\/181"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}