{"id":348,"date":"2015-05-01T09:44:53","date_gmt":"2015-05-01T09:44:53","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=348"},"modified":"2015-05-01T09:44:53","modified_gmt":"2015-05-01T09:44:53","slug":"la-cultura-enclaustrada","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/05\/01\/la-cultura-enclaustrada\/","title":{"rendered":"La cultura enclaustrada"},"content":{"rendered":"<p class=\"titulo\">A finales de la Edad Media el caudal m\u00e1s fecundo de la cultura europea pas\u00f3 de los monasterios a las universidades. Con este trasvase lo que hab\u00eda permanecido depositado en los recintos mon\u00e1sticos bajo la tutela de los monjes, preservado casi en secreto, se abri\u00f3 al debate urbano que propon\u00edan los espacios universitarios. La cultura europea entr\u00f3 en una nueva din\u00e1mica que implic\u00f3 el fin de dogmas y tab\u00faes, pero que sobre todo supuso la superaci\u00f3n del temor en la b\u00fasqueda del conocimiento. Los escritores y los fil\u00f3sofos aspiraron a romper el hermetismo de la \u00e9poca anterior, con la aspiraci\u00f3n de someter sus concepciones a p\u00fablicos cada vez m\u00e1s amplios. El uso, junto al lat\u00edn, de las lenguas populares contribuy\u00f3 a la consolidaci\u00f3n de esta tendencia, como lo demuestra el caso de Dante que, si bien escribi\u00f3 muchas de sus obras en lengua latina, reserv\u00f3 para su joya literaria, la <em>Divina Comedia<\/em>, el uso del toscano. La culminaci\u00f3n de todo ese proceso fue el Renacimiento. La invenci\u00f3n de la imprenta y la consolidaci\u00f3n de las universidades en las grandes ciudades forjaron un primer gran escenario de convergencia entre la cultura y la sociedad. Aument\u00f3 extraordinariamente el n\u00famero de lectores al tiempo que las obras literarias influ\u00edan en p\u00fablicos cada vez m\u00e1s amplios. Shakespeare, Montaigne, Bruno o Cervantes simbolizan bien esta confluencia.<\/p>\n<div class=\"texto_post\">\n<p align=\"justify\">Las universidades occidentales se consolidaron definitivamente en los siglos xix y xx (sumando las americanas a las europeas) y, aunque nunca se despojaron por completo de su origen, por as\u00ed decirlo, mon\u00e1stico, participaron activamente en la vida cultural moderna. Siempre mantuvieron una tendencia centr\u00edpeta y end\u00f3gena pero, paralelamente, muchos de sus miembros se incorporaron a los debates p\u00fablicos de su \u00e9poca y fueron grandes creadores de la literatura y del pensamiento. En estos dos \u00faltimos siglos es imposible tratar de comprender la historia cultural, o simplemente la Historia, sin atender a la funci\u00f3n de las universidades en la din\u00e1mica p\u00fablica y sin subrayar la importancia de numerosos profesores en la esfera creativa.<\/p>\n<p align=\"justify\">Pero no estoy seguro de que esto contin\u00fae siendo cierto. En los \u00faltimos lustros, y de un modo incre\u00edblemente acelerado, se ha producido una suerte de inversi\u00f3n de tendencias, a partir de la cual la universidad ha tendido a replegarse sobre s\u00ed misma, como si a\u00f1orara, en un modelo laico, su antiguo origen mon\u00e1stico. Parad\u00f3jicamente este repliegue se produce en el momento en que las tecnolog\u00edas de la comunicaci\u00f3n, como en el Renacimiento la imprenta, podr\u00edan facilitar la expansi\u00f3n de las ideas mucho m\u00e1s all\u00e1 de los circuitos universitarios.<\/p>\n<p align=\"justify\">Desde una cierta perspectiva este retraimiento es la consecuencia de un nuevo antiintelectualismo que se ha asentado poderosamente en la vida social y pol\u00edtica de principios del siglo xxi. En un reciente art\u00edculo escrito en el <em>New York Times<\/em> y titulado <em>\u00a1Profesores, os necesitamos!<\/em> Nicholas Kristof ha recordado el uso com\u00fan de la expresi\u00f3n \u00abThat&#8217;s academic\u00bb para descalificar la aportaci\u00f3n de un adversario, poniendo, adem\u00e1s, el ejemplo de su utilizaci\u00f3n por el conservador Rick Santorum para criticar los discursos de Obama. Que algo sea \u00abdemasiado acad\u00e9mico\u00bb, o sencillamente \u00abdemasiado intelectual\u00bb, es una piedra de toque com\u00fan en nuestra sociedad. El antiintelectualismo es una de las formas m\u00e1s toscas del populismo, pero parece proporcionar f\u00e1ciles r\u00e9ditos en una poblaci\u00f3n \u00e1vida por ese consumo inmediato de las cosas que la complejidad intelectual casi nunca otorga.<\/p>\n<p align=\"justify\">El problema es que la universidad actual se ha convertido, por inseguridad, cobard\u00eda u oportunismo, en c\u00f3mplice pasivo de la actitud antiintelectual que deber\u00eda combatir. En lugar de responder al desaf\u00edo arrogante de la ignorancia ofreciendo a la luz p\u00fablica propuestas creativas, la universidad del presente ha tendido a encerrarse entre sus muros. Es llamativo, a este respecto, la escasa aportaci\u00f3n universitaria a los conflictos civiles actuales, incluidas las crisis sociales o las guerras. En direcci\u00f3n contraria, el universitario ha asumido obedientemente su pertenencia a un microcosmos que debe ser preservado, a\u00fan a costa de dar la espalda a la creaci\u00f3n cultural.<\/p>\n<p align=\"justify\">Cada vez m\u00e1s alejado de lo que hab\u00eda significado la gran cultura, ese microcosmos ha elaborado complicadas normas de autopreservaci\u00f3n en las que apenas se reconoce el talante intelectual, abierto y cr\u00edtico, que se halla en la ra\u00edz renacentista de la universidad. Dicho de manera brutal: el humanista ha sido arrinconado por el bur\u00f3crata (o si se quiere, por un monje sin fe pero con gran perspicacia en la tarea de la propia conservaci\u00f3n). Naturalmente, esto no es atribuible a numerosos profesores, pero s\u00ed es el dibujo simb\u00f3lico de una tendencia general que, en s\u00ed misma, supone la destrucci\u00f3n de la universidad tal como hist\u00f3ricamente la hab\u00edamos concebido.<\/p>\n<p align=\"justify\">Es importante detenerse en las leyes que rigen en el microcosmos. Hasta hace poco lo que se valoraba en un profesor, adem\u00e1s de su capacidad para la investigaci\u00f3n, era su magisterio docente y la publicaci\u00f3n de libros relevantes en su \u00e1rea de conocimiento. Precisamente esta \u00faltima tarea era decisiva para facilitar una \u00f3smosis entre la universidad y la sociedad. El libro -y, a poder ser, el gran libro- era el instrumento b\u00e1sico en la vertebraci\u00f3n de la cultura y, simult\u00e1neamente, el desaf\u00edo que deb\u00eda afrontar el profesor que aspiraba a la madurez intelectual. La cultura occidental moderna est\u00e1 jalonada por libros que son fruto de aquel reto. Como complemento de esta tarea muchos profesores trataban de comunicarse con el p\u00fablico m\u00e1s amplio posible mediante la intervenci\u00f3n en revistas y peri\u00f3dicos.<\/p>\n<p align=\"justify\">No obstante, de un tiempo a esta parte, se ha producido un estrechamiento paulatino del anterior horizonte al mismo ritmo en que la universidad, como instituci\u00f3n, ha sacralizado el <em>paper<\/em> como medio de promoci\u00f3n profesional. En la actualidad una gran mayor\u00eda de profesores ha descartado la escritura de libros como labor primordial para concentrarse en la producci\u00f3n de <em>papers.<\/em> En muchos casos esta renuncia es dolorosa pues frustra una determinada vocaci\u00f3n creativa, a la par que investigadora, pero es la consecuencia de la propia presi\u00f3n institucional, puesto que el profesor deber ser evaluado, casi exclusivamente, por sus art\u00edculos supuestamente especializados. Como quiera que sea, el nuevo microcosmos en el que se encierra a la universidad traza una kafkiana red de relaciones y hegemon\u00edas notablemente opaca para una visi\u00f3n externa a la instituci\u00f3n. Adem\u00e1s de atender a sus labores docentes, los profesores universitarios emplean buena parte de su tiempo en la elaboraci\u00f3n de <em>papers<\/em>, textos con frecuencia herm\u00e9ticos, destinados a denominadas \u00abrevistas de impacto\u00bb, publicaciones que tienen, por lo com\u00fan, escasos lectores -siempre del propio \u00e1mbito de la especializaci\u00f3n- aunque con un gran poder ya que son las \u00fanicas \u00abque cuentan\u00bb en el momento de evaluar al universitario. En consecuencia, los profesores, sobre todo los j\u00f3venes y en situaci\u00f3n inestable, hacen cola para que sus art\u00edculos sean admitidos en publicaciones de valor desigual pero insoslayables. Se conforma as\u00ed una suerte de mandarinato que rige el microcosmos. Los profesores son calificados, mediante las evaluaciones oficiales, de acuerdo con el acatamiento a aquellas normas. La ilusi\u00f3n o vocaci\u00f3n de escribir obras de largo alcance -algo que requiere un ritmo lento, que a menudo abarca varios a\u00f1os- debe aplazarse, quiz\u00e1 para siempre.<\/p>\n<p align=\"justify\">Este ensimismamiento de la universidad, si merece cr\u00edticas crecientes en el \u00e1mbito de las ciencias, y a las que alude Nicholas Kristof en el art\u00edculo antes citado, es directamente desastroso en el de las humanidades, puesto que erradica la figura creativa e intelectualmente abierta para imponer un perfil del profesor sometido a las servidumbres de un peque\u00f1o mundo que se presenta como \u00abespecializado\u00bb pero que, en realidad, es puramente endog\u00e1mico. Lo peor es que este peque\u00f1o mundo, que alardea de rigor acad\u00e9mico, se hace impl\u00edcitamente c\u00f3mplice del antiintelectualismo populista, al refugiarse en un lenguaje oscurantista y cr\u00edptico. Podr\u00eda confeccionarse una aut\u00e9ntica antolog\u00eda del disparate si junt\u00e1ramos las exigencias burocr\u00e1ticas que, en el presente, rigen la vida universitaria. Entender las normas del microcosmos requiere tantas horas de estudio que apenas queda tiempo para estudiar lo dem\u00e1s. Comprender c\u00f3mo hacer el <em>paper<\/em> servilmente correcto obliga, por lo general, a renunciar a toda creatividad y a todo riesgo.<\/p>\n<p align=\"justify\">La cultura humanista, nacida de la libertad y de la cr\u00edtica, corre el peligro, en la actual universidad, de ser enclaustrada, como si volviera al recinto mon\u00e1stico: no a la grandeza de aquellos monasterios que conservaron el saber antiguo sino al inmovilismo dogm\u00e1tico de los que pretend\u00edan preservar los conocimientos mediante su reclusi\u00f3n. Por admirable que sea originariamente un conocimiento aprisionado es un conocimiento muerto.<\/p>\n<blockquote>\n<p align=\"justify\">Este art\u00edculo ha sido publicado por Rafael Argullol en su blog: www.elboomeran.com<\/p>\n<\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A finales de la Edad Media el caudal m\u00e1s fecundo de la cultura europea pas\u00f3 de los monasterios a las universidades. Con este trasvase lo que hab\u00eda permanecido depositado en los recintos mon\u00e1sticos bajo la tutela de los monjes, preservado casi en secreto, se abri\u00f3 al debate urbano que propon\u00edan los espacios universitarios. La cultura [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":349,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,4],"tags":[25,11,15,63],"class_list":["post-348","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-articulos","category-opinion","tag-actualidad","tag-cultura","tag-filosofia","tag-humanidades","post_format-post-format-gallery"],"jetpack_featured_media_url":"https:\/\/redfilosofia.es\/atheneblog\/wp-content\/uploads\/sites\/5\/2015\/05\/cultura2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-5C","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=348"}],"version-history":[{"count":1,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/348\/revisions"}],"predecessor-version":[{"id":350,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/348\/revisions\/350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media\/349"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}