{"id":359,"date":"2015-05-06T08:52:00","date_gmt":"2015-05-06T08:52:00","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=359"},"modified":"2015-05-06T08:52:00","modified_gmt":"2015-05-06T08:52:00","slug":"ha-matado-la-ciencia-a-la-filosofia","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/05\/06\/ha-matado-la-ciencia-a-la-filosofia\/","title":{"rendered":"\u00bfHa matado la ciencia a la filosof\u00eda?"},"content":{"rendered":"<h3 class=\"texto_grande\" style=\"text-align: justify\"><em>No tan muerta<\/em><\/h3>\n<h4 class=\"texto_grande\" style=\"text-align: justify\">Por Javier Sampedro<\/h4>\n<p style=\"text-align: justify\">Yo, se\u00f1or, soy un cient\u00edfico raro. S\u00e9 que meterse con los fil\u00f3sofos es una de las aficiones favoritas de los cient\u00edficos. <a href=\"http:\/\/elpais.com\/diario\/2004\/07\/30\/sociedad\/1091138402_850215.html\" target=\"_blank\">Francis Crick<\/a>, codescubridor de la doble h\u00e9lice del ADN, aseguraba con caracter\u00edstica mala uva que el \u00fanico fil\u00f3sofo de la historia que hab\u00eda tenido \u00e9xito era Albert Einstein. El genetista y premio Nobel Jaques Monod dedic\u00f3 un libro entero, <em>El azar y la<\/em> <em>necesidad,<\/em>a re\u00edrse de los fil\u00f3sofos marxistas, y el cosm\u00f3logo <a href=\"http:\/\/elpais.com\/tag\/stephen_w_hawking\/a\/\" target=\"_blank\">Stephen Hawking<\/a> ha declarado con gran aparato el\u00e9ctrico que \u201cla filosof\u00eda ha muerto\u201d, lo que ha dejado de piedra a los fil\u00f3sofos y seguramente a los muertos. Pero f\u00edjense en que todos esos dardos venenosos no son expresiones cient\u00edficas, sino filos\u00f3ficas, y que por tanto se autorrefutan como una paradoja de Epim\u00e9nides (ya les dije que yo era un cient\u00edfico raro).<\/p>\n<p style=\"text-align: justify\">\u00bfQu\u00e9 quiere decir Hawking con eso de que la filosof\u00eda ha muerto? Quiere decir que las cuestiones fundamentales sobre la naturaleza del universo no pueden responderse sin los datos masivos que emergen de los aceleradores de part\u00edculas y los telescopios gigantes. Quiere decir que la pregunta \u201c\u00bfpor qu\u00e9 estamos aqu\u00ed?\u201d queda fuera del alcance del pensamiento puro. Quiere decir que el progreso del conocimiento es esclavo de los datos, que su \u00fanica servidumbre es la realidad, que cuando una teor\u00eda falla la culpa es del pensador, nunca de la naturaleza. Un f\u00edsico te\u00f3rico sabe mejor que nadie que, pese a que la ciencia es solo una, hay dos formas de hacerla: generalizando a partir de los datos y pidiendo datos a partir de las ecuaciones. Einstein trabaj\u00f3 de la segunda forma, pensando de arriba abajo. Pero ese motor filos\u00f3fico tambi\u00e9n le condujo a sus grandes errores, como la negaci\u00f3n de las aplastantes evidencias de la f\u00edsica cu\u00e1ntica con el argumento de que \u201cDios no juega a los dados\u201d. Como le respondi\u00f3 Niels B\u00f6hr: \u201cNo digas a Dios lo que debe hacer\u201d.<\/p>\n<p style=\"text-align: justify\">La ciencia no matar\u00e1 a la filosof\u00eda: solo a la mala filosof\u00eda.<\/p>\n<p style=\"text-align: justify\">\n<h3 class=\"texto_grande\" style=\"text-align: justify\"><em>Una cooperaci\u00f3n fecunda<\/em><\/h3>\n<h4 class=\"texto_grande\" style=\"text-align: justify\">Por Adela Cortina<\/h4>\n<p style=\"text-align: justify\">La filosof\u00eda es un saber que se ha ocupado secularmente de cuestiones radicales, cuyas respuestas se encuentran situadas m\u00e1s all\u00e1 del \u00e1mbito de la experimentaci\u00f3n cient\u00edfica. El sentido de la vida y de la muerte, la estructura de la realidad, por qu\u00e9 hablamos de igualdad entre los seres humanos cuando biol\u00f3gicamente somos diferentes, qu\u00e9 razones existen para defender derechos humanos, c\u00f3mo es posible la libertad, en qu\u00e9 consiste una vida feliz, si es un deber moral respetar a otros aunque de ello no se siga ninguna ganancia individual o grupal, qu\u00e9 es lo justo y no s\u00f3lo lo conveniente. Sus instrumentos son la reflexi\u00f3n y el di\u00e1logo bien argumentado, que abre el camino hacia ese \u201cuso p\u00fablico de la raz\u00f3n\u201d en la vida pol\u00edtica, sin el que no hay ciudadan\u00eda plena ni aut\u00e9ntica democracia. El ejercicio de la cr\u00edtica frente al fundamentalismo y al dogmatismo es su aliado.<\/p>\n<p style=\"text-align: justify\">En sus \u00e9pocas de mayor esplendor la filosof\u00eda ha trabajado codo a codo con las ciencias m\u00e1s relevantes, y ha sido la fecundaci\u00f3n mutua de filosof\u00eda y ciencias la que ha logrado un mejor saber. Porque la filosof\u00eda que ignora los avances cient\u00edficos se pierde en especulaciones vac\u00edas; las ciencias que ignoran el marco filos\u00f3fico pierden sentido y fundamento.<\/p>\n<p style=\"text-align: justify\">Hoy en d\u00eda son especialmente las \u00e9ticas aplicadas a la pol\u00edtica, la econom\u00eda, el desarrollo, la vida amenazada y tantos otros \u00e1mbitos las que han mostrado que el imperialismo de un solo saber, sea el que fuere, es est\u00e9ril, que la cooperaci\u00f3n sigue siendo la opci\u00f3n m\u00e1s fecunda. Habr\u00e1 que mantener, pues, la ense\u00f1anza de la \u00e9tica y de la filosof\u00eda en la ESO y en el bachillerato, no vaya a ser que, al final, cient\u00edficos como Hawking o <a href=\"http:\/\/cultura.elpais.com\/cultura\/2014\/09\/18\/babelia\/1411040618_425569.html\" target=\"_blank\">Dawkins<\/a> acaben d\u00e1ndole la raz\u00f3n a la\u00a0<a href=\"http:\/\/elpais.com\/tag\/lomce_ley_organica_mejora_calidad_ensenanza\/a\/\" target=\"_blank\">LOMCE<\/a>.<\/p>\n<blockquote><p>Art\u00edculo publicado por Javier Sampedro y Adela Cortina en: www.elpais.com<\/p>\n<p>Fecha: 3 de enero de 2015.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>No tan muerta Por Javier Sampedro Yo, se\u00f1or, soy un cient\u00edfico raro. S\u00e9 que meterse con los fil\u00f3sofos es una de las aficiones favoritas de los cient\u00edficos. Francis Crick, codescubridor de la doble h\u00e9lice del ADN, aseguraba con caracter\u00edstica mala uva que el \u00fanico fil\u00f3sofo de la historia que hab\u00eda tenido \u00e9xito era Albert Einstein. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,4],"tags":[35,15,81,10],"class_list":["post-359","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-articulos","category-opinion","tag-ciencia","tag-filosofia","tag-innovacion","tag-pensamiento","post_format-post-format-gallery"],"jetpack_featured_media_url":"https:\/\/redfilosofia.es\/atheneblog\/wp-content\/uploads\/sites\/5\/2015\/05\/ciencia-y-moralidad-2.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-5N","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":1,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"predecessor-version":[{"id":361,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/359\/revisions\/361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media\/360"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}