{"id":397,"date":"2015-05-12T09:55:21","date_gmt":"2015-05-12T09:55:21","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=397"},"modified":"2015-05-12T09:55:21","modified_gmt":"2015-05-12T09:55:21","slug":"carlos-garcia-gual-vivir-solo-en-el-presente-es-vivir-en-una-prision-intelectual","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/05\/12\/carlos-garcia-gual-vivir-solo-en-el-presente-es-vivir-en-una-prision-intelectual\/","title":{"rendered":"Carlos Garc\u00eda Gual: \u00abVivir s\u00f3lo en el presente es vivir en una prisi\u00f3n intelectual\u00bb"},"content":{"rendered":"<p><a href=\"http:\/\/www.elcultural.com\/revista\/letras\/Voyage-du-jeune-Anacharsis\/33818\">Carlos Garc\u00eda Gual<\/a> (Palma de Mallorca, 1943) declara que a lo largo de su vida ha escrito sobre todo libros manejables para los lectores. \u00abYo soy un autor de pr\u00f3logos y de libros de bolsillo\u00bb, dice, y esboza una sonrisa. Pero la realidad es bien distinta. <strong>Dos veces premio nacional de Traducci\u00f3n<\/strong> (en 1978 por su versi\u00f3n de <em>Vida y haza\u00f1as de Alejandro de Macedonia<\/em>, de Pseudo Cal\u00edstenes; en 2002 por el conjunto de su obra), catedr\u00e1tico de Filolog\u00eda Griega, investigador y estudioso en ampl\u00edsimos terrenos, art\u00edfice de la legendaria\u00a0<a href=\"http:\/\/www.elcultural.com\/noticias\/letras\/Gredos-siete-decadas-de-resistencia\/6371\">Biblioteca Cl\u00e1sica de Gredos<\/a>, Garc\u00eda Gual estuvo hace unos d\u00edas en la Fundaci\u00f3n Juan March para repasar, en compa\u00f1\u00eda de <a href=\"http:\/\/www.elcultural.com\/noticias\/letras\/Javier-Goma-Los-libros-me-sirven-un-gin-tonic-de-la-vida\/5996\">Javier Gom\u00e1<\/a>, su trayectoria intelectual. Su infancia en Palma, la formaci\u00f3n primera en la biblioteca de su abuelo, Barcelona y Madrid y aquella vieja Facultad de Letras a la que ha estado vinculado durante toda su vida profesional. Antes del acto el profesor se sent\u00f3 a hablar con El Cultural.<\/p>\n<p><strong>Pregunta.-<\/strong> \u00bfC\u00f3mo ve alguien que ha dedicado su carrera a la docencia de los saberes cl\u00e1sicos el arrinconamiento de las Humanidades en la universidad espa\u00f1ola?<br \/>\n<strong>Respuesta.-<\/strong> Con pesimismo. Veo que el horizonte es oscuro en un doble sentido. Por un lado, hay un desprestigio general de las Humanidades por culpa de <strong>una sociedad cada vez m\u00e1s pragm\u00e1tica<\/strong> que busca el bienestar econ\u00f3mico y nada m\u00e1s. Y por otro lado, hay un problema dentro de la propia universidad, un problema de falta de fondos; cada vez hay menos profesores, una mayor penuria para comprar libros, para acondicionar despachos&#8230;<\/p>\n<p><strong>P.-<\/strong> Est\u00e1 la sociedad, pero los pol\u00edticos son los primeros que desprecian las humanidades. Es rar\u00edsimo que alguno las nombre en sus discursos.<br \/>\n<strong>R.- <\/strong>Es cierto. Y cuando hablan de cultura es siempre desde el plano econ\u00f3mico, como en el caso del IVA cultural. Pero de la orientaci\u00f3n cultural, <strong>de hacia d\u00f3nde vamos culturalmente ninguno habla<\/strong>. Creo que existe una crisis que opera en diversos frentes. Se habla mucho de la crisis que afecta a las editoriales, que venden menos libros por culpa de la pirater\u00eda de los contenidos, pero esa crisis tiene su origen, creo, en algo tan simple como que la gente lee mucho menos. Aunque es verdad que en Espa\u00f1a se leen bastantes libros en comparaci\u00f3n con otros pa\u00edses, la gente lee novelas y cosas bastante ligeras. Ensayos o libros de m\u00e1s nivel cultural se leen muy poco, por no decir nada.<\/p>\n<p><strong>P.-<\/strong> Usted ha dado clase toda su vida en Filolog\u00eda. \u00bfTambi\u00e9n los alumnos leen menos?<br \/>\n<strong>R.-<\/strong> Leen muy poco. Gastan su tiempo atendiendo diversas pantallas y <strong>creen adem\u00e1s que toda la sabidur\u00eda del mundo est\u00e1 en Google<\/strong>. Yo daba por supuesto que los alumnos de segundo o tercer curso de Cl\u00e1sicas, que es cuando llegan a mi asignatura, hab\u00edan le\u00eddo una serie de libros b\u00e1sicos, y no es as\u00ed. A m\u00ed se me han quejado alumnos que dec\u00edan que no ten\u00eda derecho a mandarles leer la <em>Il\u00edada<\/em> porque era muy gorda.<\/p>\n<p><strong>P.-<\/strong> Es llamativo porque estudiar cl\u00e1sicas hoy, tal y como est\u00e1 el mercado, solo puede ser vocacional.<br \/>\n<strong>R.-<\/strong> En realidad lo fue siempre, pero hoy es una vocaci\u00f3n m\u00e1s peligrosa todav\u00eda. Los de mi generaci\u00f3n al menos encontr\u00e1bamos un puesto de trabajo al salir de la universidad. La ense\u00f1anza media ten\u00eda sus profesores de griego, de lat\u00edn. Ahora esto ya no es as\u00ed en la ense\u00f1anza p\u00fablica y mucho menos en los colegios concertados, donde se consideran gravosas ese tipo de asignaturas.<\/p>\n<p><strong>P.-<\/strong> Cree, entonces, que el problema del nivel de los alumnos ha de atajarse desde los planes de ense\u00f1anza primaria y media.<br \/>\n<strong>R.-<\/strong> Creo que s\u00ed. A m\u00ed me da pena el descenso de la secundaria. Yo fui profesor de secundaria durante cuatro a\u00f1os en el Instituto Beatriz Galindo y era un instituto estupendo. Tengo amigos que siguen dando clase a esos niveles y est\u00e1n muy dolidos, incluso por hechos de disciplina que antes no se daban. Es verdad que ha aumentado mucho el alumnado, pero el nivel ha bajado tanto que no creo que pueda explicarse por esta raz\u00f3n. Y ya en la universidad yo echo de menos lo que en mi \u00e9poca se llamaban cursos comunes. Creo que la especializaci\u00f3n empieza muy pronto y cuando eso se hace sobre <strong>una base cultural inexistente<\/strong> es peligros\u00edsimo.<\/p>\n<p><strong>P.-<\/strong> Conv\u00e9nzame, como si fuera un adolescente indeciso, de que son importantes las humanidades, de que debo estudiar y conocer la cultura cl\u00e1sica.<br \/>\n<strong>R.-<\/strong> Pues mire: ahora hay la creencia de que basta con saber manejarse en el presente. Pero <strong>hay que conocer bien el pasado para entender qu\u00e9 es la vida<\/strong>. Quien vive solamente en un espacio, y sobre todo en un tiempo determinado y no conoce m\u00e1s, es como si viviera en una especie de prisi\u00f3n intelectual. Sin entender por qu\u00e9 estamos aqu\u00ed y c\u00f3mo hemos llegado a d\u00f3nde estamos, creo que se reduce mucho lo que es la vida. Yo le dir\u00eda que tiene que leer los grandes libros, o algunos de los grandes libros: el <em>Quijote<\/em>, la <em>Il\u00edada<\/em>, a Shakespeare. As\u00ed entender\u00e1 hasta d\u00f3nde puede llegar el ser humano.<\/p>\n<p><strong>P.-<\/strong> \u00bfEn qu\u00e9 aspectos de nosotros, de lo que somos, podemos rastrear la influencia de los mitos griegos?<br \/>\n<strong>R.-<\/strong> Bueno, los mitos son una parte limitada del mundo griego. Reflejan la gran imaginaci\u00f3n de los griegos, su capacidad para crear un mundo de dioses y diosas de enorme humanidad. Los dioses griegos son tremendamente humanos, son tambi\u00e9n divertidos, pat\u00e9ticos&#8230; <strong>la sociedad griega, que est\u00e1 en la base de la nuestra<\/strong>, sinti\u00f3 la libertad, la humanidad que permiti\u00f3 la democracia, la filosof\u00eda, las matem\u00e1ticas. Los griegos eran viajeros: Her\u00f3doto, Tuc\u00eddides&#8230; Cuando uno lo compara con otras civilizaciones se da cuenta de que los griegos han sido el pueblo con m\u00e1s capacidad de aventura que ha existido.<\/p>\n<p><strong>P.-<\/strong> \u00bfQu\u00e9 equilibrio mantienen en nuestra cultura la tradici\u00f3n griega y la judeocristiana?<br \/>\n<strong>R.-<\/strong> Yo creo que tenemos mucho de los griegos; m\u00e1s de lo que pensamos. Tenemos ese sentido de la libertad, de lo importante que es la conciencia individual. De ellos nos viene el gusto por el arte, la apertura hacia el mundo. Todo esto es muy griego. El cristianismo, aunque elimin\u00f3 la religi\u00f3n antigua, conserv\u00f3 mucho de la cultura pagana. Por ejemplo, la poes\u00eda. La mitolog\u00eda pas\u00f3 a formar parte de las ficciones po\u00e9ticas, pero permaneci\u00f3. La noci\u00f3n sobre el alma, la inmortalidad del alma, la \u00e9tica, la conducta social, eso ya estaba en Plat\u00f3n y el cristianismo lo tom\u00f3 de \u00e9l y lo ha sabido conservar. Esa es la gran herencia cl\u00e1sica, que atraviesa la Edad Media y se renueva con el Renacimiento.<\/p>\n<p><strong>P.-<\/strong> \u00bfRecuerda cuando decidi\u00f3 que quer\u00eda dedicarse a la Filolog\u00eda Cl\u00e1sica?<br \/>\n<strong>R.- <\/strong>Yo iba a hacer letras en la universidad y me gustaban por igual la filosof\u00eda, la literatura y el mundo antiguo, pero me decid\u00ed sobre todo porque hab\u00eda muy buenos profesores de Griego. Filosof\u00eda me desilusion\u00f3 un poco y en Literatura no tuve tampoco mucha suerte. En cambio en Griego estaban Adrados, Laso, Fern\u00e1ndez Galiano&#8230; eran excelentes profesores. Y aut\u00e9nticas referencias a nivel internacional. Entonces en la Facultad de Letras el Griego ten\u00eda mucho prestigio.<\/p>\n<p><strong>P.- <\/strong>\u00bfY ahora?<br \/>\n<strong>R.-<\/strong> Ahora hay buenos especialistas, pero son m\u00e1s limitados.<\/p>\n<p><strong>P.- <\/strong>Volviendo a los textos griegos, es curioso que la <em>Odisea<\/em> se tradujera al espa\u00f1ol por primera vez en el siglo XVI y la <em>Il\u00edada<\/em> tardara a\u00fan dos siglos en llegar&#8230;<br \/>\n<strong>R.-<\/strong> S\u00ed. Hoy tenemos ya muchas traducciones de ambas en castellano, como unas veinticuatro de la<em> Il\u00edada<\/em> y unas doce de la <em>Odisea<\/em>, y en ingl\u00e9s muchas m\u00e1s. Steiner bromeaba con esto, con que todos los a\u00f1os saliera una nueva traducci\u00f3n que ven\u00eda a ser la definitiva. Pero la primera traducci\u00f3n de la <em>Odisea<\/em>, la de Gonzalo P\u00e9rez, que es de 1580, lleg\u00f3 aqu\u00ed antes de que el texto estuviera disponible en ingl\u00e9s. Era una \u00e9poca en que Espa\u00f1a ten\u00eda una proyecci\u00f3n importante hacia Europa y hacia Am\u00e9rica y fue entonces cuando se tradujo tambi\u00e9n a Virgilio. La de Garc\u00eda Malo de la <em>Il\u00edada<\/em>, la del siglo XVIII, est\u00e1 bien, pero sobre todo es muy buena la segunda que se hizo, la de Hermosilla, que era preceptor de po\u00e9tica e hizo una traducci\u00f3n en endecas\u00edlabos que todav\u00eda se puede leer hoy con mucho agrado.<\/p>\n<p><strong>P.-<\/strong> Su labor como traductor ha obtenido el m\u00e1ximo reconocimiento a nivel nacional en dos ocasiones, en 2002 por el conjunto de su obra. \u00bfPiensa que el traductor es, todav\u00eda hoy, una figura no lo suficientemente reconocida?<br \/>\n<strong>R.- <\/strong>Eso ha ocurrido siempre. Ahora hay muy buenos traductores, pero siguen estando mal pagados, sobre todo porque no es lo mismo traducir un <em>best seller<\/em>, que se vende enseguida y el traductor, que tiene contrato con la editorial, cobra r\u00e1pido, que traducir por tu cuenta y encima cl\u00e1sicos o libros de ensayo. Es muy importante reivindicar el papel del traductor porque es el que convierte en universal un texto.<\/p>\n<p><strong>P.-<\/strong> En los textos griegos en concreto, \u00bfqu\u00e9 se pierde en la traducci\u00f3n?<br \/>\n<strong>R.-<\/strong> La m\u00fasica, la belleza del l\u00e9xico&#8230; pero yo creo que siempre se conserva lo fundamental. Esto depende de los g\u00e9neros. En la poes\u00eda siempre parece que se pierde algo m\u00e1s. En prosa menos, en textos cient\u00edficos no se pierde nada, tambi\u00e9n porque los t\u00e9rminos son m\u00e1s universales.<\/p>\n<p><strong>P.-<\/strong> Se ha ocupado de la novela en sus obras, de sus or\u00edgenes y su desarrollo. Alguna vez ha declarado que le falta imaginaci\u00f3n para escribir una.<br \/>\n<strong>R.- <\/strong>S\u00ed, es que soy poco imaginativo&#8230;. Quiz\u00e1 estoy tambi\u00e9n incapacitado porque he le\u00eddo demasiadas.<\/p>\n<p><strong>P.-<\/strong> \u00bfProcura estar al tanto de las novedades editoriales? \u00bfLee novela contempor\u00e1nea?<br \/>\n<strong>R.- <\/strong>No demasiado. <strong>Leo muy poca novela espa\u00f1ola<\/strong>, la verdad. Pero s\u00ed que leo bastante novela polic\u00edaca. Me gustan las de <a href=\"http:\/\/www.elcultural.com\/revista\/especial\/Leonardo-Padura-Nadie-se-va-del-todo-de-Cuba\/35913\">Leonardo Padura<\/a>, las de <a href=\"http:\/\/www.elcultural.com\/noticias\/letras\/John-Banville-Mi-mayor-ambicion-seria-escribir-una-novela-negra-sin-crimen\/5964\">Benjamin Black<\/a>. Soy un lector muy disperso y siempre tengo abiertos varios libros.<\/p>\n<p><strong>P.-<\/strong> \u00bfC\u00f3mo ve la cr\u00edtica literaria actual?<br \/>\n<strong>R.-<\/strong> Mal, muy mal, quiz\u00e1 algo mejor en suplementos como El Cultural, Babelia o el de ABC. Yo creo que <strong>una buena revista de cr\u00edtica literaria debe tener sus cr\u00edticos serios, de siempre<\/strong>, que tengan cierto prestigio y no les importe hacer cr\u00edticas duras cuando proceda. Pero lo que tenemos ahora no es eso. Predomina la cr\u00edtica blanda y elogiosa y eso es el lector quien lo paga, pues no se siente orientado. Se rese\u00f1a adem\u00e1s mucho <em>best seller<\/em>, y estos son libros que se ponen de moda pero no sirven para nada. Creo que han ido desapareciendo algunos cr\u00edticos importantes y no est\u00e1 habiendo un recambio claro. Est\u00e1 todo muy mediatizado, existen presiones de las editoriales. En ese sentido me gusta m\u00e1s la cr\u00edtica de cine, que orienta mucho mejor. \u00a1Al menos sabes, al terminar de leerla, si la pel\u00edcula es buena o mala! Eso cada vez ocurre menos en la cr\u00edtica literaria, que es ambigua o abiertamente elogiosa.<\/p>\n<p><strong>P.- <\/strong>Usted ejerce la cr\u00edtica, pero me parece que cada vez menos. \u00bfTiene que ver con que ha dejado de confiar en su utilidad?<br \/>\n<strong>R.-<\/strong> En realidad es porque me quita mucho tiempo. <strong>La cr\u00edtica es un oficio muy duro porque hay que leerse bien los textos<\/strong>. Eso o haces propaganda, que es bien distinto y mucho m\u00e1s c\u00f3modo porque ni siquiera hay que leer los libros.<\/p>\n<p><strong>P.-<\/strong> Hay quien defiende que la cr\u00edtica negativa no tiene demasiado sentido: si un libro no es bueno, no se da y ese espacio queda para rese\u00f1ar uno que s\u00ed lo es.<br \/>\n<strong>R.-<\/strong> Eso puede tener sentido respecto a autores j\u00f3venes; yo entiendo que con los j\u00f3venes no hay que ser cruel, o no se debe. Pero con los consagrados se puede, aunque nadie se atreve. Por ejemplo, meterse con P\u00e9rez-Reverte: eso no lo hace nadie.<\/p>\n<p><strong>P.-<\/strong> \u00bfLe gusta alguno de los escritores consagrados?<br \/>\n<strong>R.-<\/strong> Alguno s\u00ed. Le\u00ed los primeros libros de <a href=\"http:\/\/www.elcultural.com\/revista\/letras\/Antonio-Munoz-Molina-Los-decentes-que-miran-hacia-otro-lado-agravan-el-desastre\/35513\">Mu\u00f1oz Molina<\/a> y de <a href=\"http:\/\/www.elcultural.com\/noticias\/letras\/Javier-Marias-La-justicia-se-asusta-ante-los-crimenes-mas-terribles\/6845\">Javier Mar\u00edas<\/a>; los actuales ya menos, quiz\u00e1 porque me he cansado. Me gustaba <a href=\"http:\/\/www.elcultural.com\/noticias\/letras\/Eduardo-Mendoza-Ahora-la-literatura-es-un-entretenimiento-de-y-para-zombies\/5166\">Mendoza<\/a> en sus primeros libros, ahora me gusta menos con esta cosa c\u00f3mica. Y Javier Mar\u00edas me gusta poco ahora: creo que sus elucubraciones cada vez le comen m\u00e1s terreno a las novelas y las hacen dif\u00edciles de digerir. Ocasionalmente leo poes\u00eda, pero ya muy poco. \u00a1Es que leer bien poes\u00eda lleva mucho tiempo! Estoy al tanto m\u00e1s o menos de los de mi generaci\u00f3n, pero me supera mucho la cantidad de poes\u00eda que se publica.<\/p>\n<p><strong>P.-<\/strong> \u00bfY c\u00f3mo es su relaci\u00f3n con los textos cl\u00e1sicos? \u00bfA\u00fan disfruta de su lectura?<br \/>\n<strong>R.-<\/strong> S\u00ed, claro. Soy un lector continuo pero bastante poco original. Ahora hago m\u00e1s bien calas, voy a un pasaje, lo busco, lo leo y casi siempre me dice cosas nuevas. <strong>Esa es la magia de los cl\u00e1sicos<\/strong>. Uno de mis \u00faltimos libros, <em><a href=\"http:\/\/www.elcultural.com\/revista\/letras\/Sirenas-Seducciones-y-metamorfosis\/34767\">Sirenas<\/a><\/em>, es un poco esto, la vuelta a estos pasajes; las sirenas en Homero, en Apolonio Rodio&#8230; leo un poco a saltos, esa es la verdad.<\/p>\n<p><strong>P.-<\/strong> \u00bfY qui\u00e9nes son sus autores de cabecera?<br \/>\n<strong>R.-<\/strong> Soy muy cl\u00e1sico: Homero, Plat\u00f3n. Vuelvo a los de siempre. \u00daltimamente he traducido <em>Edipo Rey<\/em>, de S\u00f3focles, y me sigue pareciendo una obra magn\u00edfica. Las <em>Bacantes<\/em> de Eur\u00edpides tambi\u00e9n. Tambi\u00e9n me gustan mucho <em>Las vidas de los fil\u00f3sofos<\/em>, de Di\u00f3genes Laercio, que es el texto m\u00e1s divertido de toda la cultura griega. Son textos que me han acompa\u00f1ado siempre; es m\u00e1s, muchos de ellos los le\u00ed por primera vez siendo muy joven, en la biblioteca de mi abuelo.<\/p>\n<blockquote><p>Este art\u00edculo ha sido publicado por Alberto Gordo en: www.elcultural.com<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Garc\u00eda Gual (Palma de Mallorca, 1943) declara que a lo largo de su vida ha escrito sobre todo libros manejables para los lectores. \u00abYo soy un autor de pr\u00f3logos y de libros de bolsillo\u00bb, dice, y esboza una sonrisa. Pero la realidad es bien distinta. Dos veces premio nacional de Traducci\u00f3n (en 1978 por [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[87,63,10],"class_list":["post-397","post","type-post","status-publish","format-gallery","hentry","category-entrevistas","tag-clasicos","tag-humanidades","tag-pensamiento","post_format-post-format-gallery"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-6p","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=397"}],"version-history":[{"count":1,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/397\/revisions"}],"predecessor-version":[{"id":399,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/397\/revisions\/399"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}