{"id":467,"date":"2015-06-28T16:20:23","date_gmt":"2015-06-28T16:20:23","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=467"},"modified":"2015-06-28T16:20:23","modified_gmt":"2015-06-28T16:20:23","slug":"los-60-esplendidos-anos-de-cronicas-marcianas-el-libro-que-cambio-la-ciencia-ficcion","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/06\/28\/los-60-esplendidos-anos-de-cronicas-marcianas-el-libro-que-cambio-la-ciencia-ficcion\/","title":{"rendered":"Los 60 espl\u00e9ndidos a\u00f1os de &#8216;Cr\u00f3nicas Marcianas&#8217;, el libro que cambi\u00f3 la ciencia ficci\u00f3n"},"content":{"rendered":"<p><strong>Minotauro reedita la colecci\u00f3n de relatos que convirti\u00f3 a Ray Bradbury en un autor de \u00e9xito y traspas\u00f3 los l\u00edmites del g\u00e9nero.<\/strong><\/p>\n<p>\u00bfQu\u00e9 ha hecho este hombre de Illinois, me pregunto al cerrar las p\u00e1ginas de su libro, para que episodios de la conquista de otro planeta me llenen de terror y soledad? \u00bfC\u00f3mo pueden tocarme estas fantas\u00edas y de una manera tan \u00edntima?\u00bb Las preguntas se las hac\u00eda <strong>Jorge Luis Borges <\/strong>hace ahora 60 a\u00f1os. El <em>hombre de Illinois<\/em> era <strong>Ray Bradbury<\/strong> (1920-2012), autor de obras maestras como <em>Farenheit 451 <\/em>(1953), y el libro en cuesti\u00f3n <em>Cr\u00f3nicas marcianas. <\/em>La \u00fanica inexactitud, quiz\u00e1s, era llamar a Bradbury <em>hombre de Illinois<\/em>, porque aunque hab\u00eda nacido en este estado, viv\u00eda en Los \u00c1ngeles desde que ten\u00eda 14 a\u00f1os y en esta ciudad muri\u00f3. Por todo lo dem\u00e1s, las preguntas siguen vigentes y surgen con cada relectura. \u00bfC\u00f3mo lo hizo?<\/p>\n<p>\u00abLa he estado revisando. Tengo un ejemplar de hace 30 a\u00f1os. Es uno de esos libros de los que no se hace, de una ambici\u00f3n tremenda. Lo pongo al mismo nivel que los trabajos de <strong>Isaac<\/strong> <strong>Asimov<\/strong>, al mismo nivel que <em>Fundaci\u00f3n<\/em>\u00ab. Los elogios los afirma ahora, seis d\u00e9cadas despu\u00e9s, el escritor y cient\u00edfico <a href=\"https:\/\/es.wikipedia.org\/wiki\/Juan_Jos%C3%A9_G%C3%B3mez_Cadenas\" target=\"_blank\"><strong>Juan Jos\u00e9 G\u00f3mez Cadenas<\/strong><\/a>, quien se declara admirador de esta novela.<\/p>\n<p>Con motivo del 60 aniversario de su publicaci\u00f3n en Espa\u00f1a, Ediciones Minotauro ha decidido recuperar <em>Cr\u00f3nicas marcianas<\/em>, el libro con el que inici\u00f3 su andadura en 1955. Y lo ha hecho con una edici\u00f3n especial, numerada y con portada ilustrada por <a href=\"mailto:@olivaresilustra\" target=\"_blank\"><strong>Javier Olivares<\/strong><\/a>, en la que se incluye un nuevo relato, \u2018Los globos de fuego&#8217;, que se hab\u00eda publicado antes en la colecci\u00f3n <em>El hombre ilustrado<\/em>. Adem\u00e1s, esta nueva edici\u00f3n\u00a0contiene cuatro ilustraciones de <strong>Edward Miller <\/strong>y dos pr\u00f3logos que no estaban presentes en la original por evidentes razones cronol\u00f3gicas: uno a cargo del propio Bradbury, escrito en 1997, y otro de la mano del escritor <strong>John Scalzi<\/strong>, redactado en 2009.<\/p>\n<p>Se aglutinan pues 27 relatos y se mantiene en 26 de ellos la traducci\u00f3n original de <strong><a href=\"http:\/\/cultura.elpais.com\/cultura\/2013\/06\/26\/actualidad\/1372244459_905362.html\">Francisco Porr\u00faa<\/a><\/strong> (1922-2013), hist\u00f3rico editor criado en la pampa argentina que fue el visionario que trajo a Espa\u00f1a esta novela y otras obras maestras de la Literatura universal como <em>Rayuela<\/em> de <strong>Julio Cort\u00e1zar<em>,<\/em><\/strong> o del g\u00e9nero fant\u00e1stico como la obra completa de <strong>Tolkien.<\/strong> Aunque en el caso de <em>Cr\u00f3nicas marcianas<\/em> cabe reconocer que su elecci\u00f3n fue azarosa.<\/p>\n<p>Seg\u00fan confes\u00f3 en una <a href=\"http:\/\/www.pagina12.com.ar\/diario\/suplementos\/libros\/10-3457-2009-06-07.html\">entrevista concedida en 2009<\/a> al periodista argentino <strong>Patricio Lennard<\/strong> para <em><a href=\"http:\/\/www.pagina12.com.ar\/diario\/ultimas\/index.html\">P\u00e1gina 12<\/a><\/em>, Porr\u00faa eligi\u00f3 el libro para ser el debut de Minotauro despu\u00e9s de verlo citado en la revista de <strong>Jean-Paul Sartre<\/strong> <em>Les Temps Modernes.<\/em> \u00abMe encontr\u00e9 con un art\u00edculo que se llamaba algo as\u00ed como <em>Qu&#8217;est que c&#8217;est la science-fiction?<\/em> (\u00bfQu\u00e9 es la ciencia ficci\u00f3n?), y all\u00ed se mencionaba a un escritor norteamericano de apellido Bradbury. Entonces fui a una librer\u00eda a la que iba habitualmente, consegu\u00ed un libro suyo en ingl\u00e9s y eso fue lo primero que le\u00ed de la ciencia ficci\u00f3n moderna\u00bb.<\/p>\n<p>Una novela que surgi\u00f3 como tal tambi\u00e9n por azar. Seg\u00fan explica el propio Bradbury en el nuevo pr\u00f3logo incorporado al libro, fue tras un viaje a Nueva York cuando se plante\u00f3 darle una estructura que ya le rondaba la cabeza. Su amigo <strong>Norman Corwin, <\/strong>(\u00abel primero que me escuch\u00f3 contar las historias de Marte\u00bb) le puso en contacto con quien ser\u00eda futuro editor <strong>Walter I. Bradbury <\/strong>(ning\u00fan parentesco). Este le dijo: \u00abTodos esos cuentos marcianos, \u00bfno podr\u00eda usted juntarlos armado de aguja e hilo, coserlos, para dar forma a <em>Cr\u00f3nicas marcianas<\/em>?\u00bb. Bradbury, que hab\u00eda crecido obsesionado con el libro <em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Winesburg,_Ohio_%28novel%29\">Winesburg, Ohio<\/a><\/em>, de <strong>Sherwood Anderson<\/strong>, un conjunto de relatos sobre un peque\u00f1o pueblo de Estados Unidos, le respondi\u00f3 al d\u00eda siguiente llev\u00e1ndole el plan para <em>Cr\u00f3nicas marcianas<\/em>. Ya ten\u00eda su propio <em>Winesburg, Ohio<\/em>.<\/p>\n<p><em>Cr\u00f3nicas marcianas <\/em>apareci\u00f3 publicada a finales de la primavera de 1950 y obtuvo pocas cr\u00edticas al principio. El desinter\u00e9s no dur\u00f3 mucho. Pront\u00f3 salt\u00f3 las fronteras de la ciencia ficci\u00f3n y lleg\u00f3 a los cen\u00e1culos literarios m\u00e1s serios. Una novela popular sojuzg\u00f3 a los <em>popes<\/em>. Entre los fans, otro autor imprescindible del g\u00e9nero, <strong>Aldous Huxley<\/strong>, quien hab\u00eda publicado veinte a\u00f1os antes una de las distop\u00edas m\u00e1s famosas de la Historia: <em>Un mundo feliz<\/em> (1932). Durante un encuentro entre Bradbury, Huxley y el fil\u00f3sofo ingl\u00e9s <strong>Gerald Heard<\/strong>, en casa del primero, los dos escritores brit\u00e1nicos le preguntaron:<\/p>\n<p>\u2014\u00bfSabe qu\u00e9 es usted?<\/p>\n<p>\u2014\u00bfQu\u00e9?\u00a0 \u2014respondi\u00f3 Bradbury desconcertado.<\/p>\n<p>\u2014Un poeta \u2014dijeron.<\/p>\n<p>Un poeta con Arcadia propia, en este caso triste, y nombre real: Marte. \u00abEl tema de Marte nos obsesiona porque es un espejo de la Tierra. El ciudadano moderno sigue so\u00f1ando con ese Marte que no es sino un reflejo de nuestro mundo, con viajar hasta all\u00ed\u00bb, dice Cadenas. Un Marte en el que da igual la rigurosidad cient\u00edfica. Como recuerda Bradbury en su pr\u00f3logo, \u00abhasta los f\u00edsicos de culo duro de CalTech aceptan la atm\u00f3sfera compuesta por ox\u00edgeno fraudulento que he liberado en Marte\u00bb. \u00abLo m\u00e1s rese\u00f1able es que la ciencia es una excusa, y adem\u00e1s barata\u00bb, comenta de nuevo el f\u00edsico valenciano. \u00abSu Marte es de mentira, como el de <strong>Edgar Rice Burroughs <\/strong>y los libros de la serie sobre John Carter como <em>Una princesa de Marte. <\/em><strong>Lo que le interesan a Bradbury son los problemas sociales y los psicol\u00f3gicos<\/strong>\u00ab, a\u00f1ade. Nada de leyes rob\u00f3ticas. Nada de n\u00fameros. S\u00f3lo el alma.<\/p>\n<p>Pese a su magisterio, o quiz\u00e1s por su grandeza, Bradbury no tuvo novelistas seguidores de inmediato. \u00bfC\u00f3mo imitar lo insuperable? \u00bfQui\u00e9n podr\u00eda hacerlo mejor? \u00abLo mismo que Asimov abre tres o cuatro canales a \u00e9l no le sigue tanta gente\u00bb, constata G\u00f3mez Cadenas. Su senda, dice, se retom\u00f3 de manera notoria a partir de los a\u00f1os 90, con la serie de libros <em>Marte Rojo, Marte Azul <\/em>y <em>Marte Verde<\/em>, la <em>Trilog\u00eda Marciana <\/em>de <strong>Kim Stanley Robinson<\/strong>, herederos directos del trabajo de Bradbury.<\/p>\n<p>Los nuevos narradores no ocultan ya su admiraci\u00f3n hacia \u00e9l y hacen bandera de su obra. As\u00ed lo cree por ejemplo el escritor valenciano <a href=\"https:\/\/es.wikipedia.org\/wiki\/Juan_Miguel_Aguilera\" target=\"_blank\"><strong>Juan Miguel Aguilera<\/strong><\/a>, autor, entre otros libros y textos, del gui\u00f3n de <em>N\u00e1ufragos<\/em>, la pel\u00edcula de la cineasta valenciana Luna ambientada en Marte. \u00ab<em>Cr\u00f3nicas marcianas<\/em> es un referente para la gente de toda nuestra generaci\u00f3n\u00bb, dice Aguilera, \u00absobre todo porque \u00e9l no era un escritor de ciencia ficci\u00f3n sino de Literatura. En su \u00e9poca ya se sab\u00eda c\u00f3mo era Marte y se sab\u00eda que no pod\u00edan ir con carretas como el Oeste. A \u00e9l todo eso le da igual porque lo que quer\u00eda era hacer una met\u00e1fora sobre el encuentro de civilizaciones, de culturas\u00bb, explica.<\/p>\n<p>La huella de <em>Cr\u00f3nicas marcianas<\/em> ya es indeleble y se encuentra en gran parte de los narradores actuales.\u00bbMe ha influido bastante porque casi todas mis novelas han tratado el tema del encuentro entre culturas\u00bb, comenta Aguilera. Scalzi, quien ley\u00f3 <em>Cr\u00f3nicas marcianas<\/em> por encargo de un profesor en sexto de primaria, dice en el pr\u00f3logo que este libro le ense\u00f1\u00f3 \u00ablo que las palabras pueden hacer\u00bb. <strong>\u00abMe mostr\u00f3 la magia\u00bb<\/strong>, a\u00f1ade. Bradbury como el gran mago.<\/p>\n<p>\u00abEs un adelantado a su tiempo\u00bb, insiste G\u00f3mez Cadenas. \u00abPuso el g\u00e9nero patas arriba\u00bb, dice G\u00f3mez Cadenas. \u00abHubo otros escritores que apostaron por la calidad cient\u00edfica, pero \u00e9l apuesta por calidad literaria. La parte psicol\u00f3gica me interesa mucho, la percepci\u00f3n de la realidad&#8230; la construcci\u00f3n es como de tragedia. Cambia la manera de pensar y le da calidad literaria a la ciencia ficci\u00f3n. Era <strong>un aut\u00e9ntico escritor<\/strong>\u00ab.<\/p>\n<p>Por eso, al margen de su car\u00e1cter acient\u00edfico, lo realmente importante del libro es su capacidad de adentrarse en el alma humana con un estilo cuidado y atractivo. Esa es posiblemente la clave que explica la vigencia de un libro \u00fanico, que reinvent\u00f3 el g\u00e9nero y que ahora ha vuelto a las estanter\u00edas de la mano de la editorial que lo trajo a Espa\u00f1a, Minotauro. No se trata de una novela de ciencia ficci\u00f3n en sentido estricto. Es m\u00e1s. Es una met\u00e1fora sobre el ser humano. Los c\u00f3digos y usos narrativos de la ciencia ficci\u00f3n se pusieron al servicio de la descripci\u00f3n de tipos, de personas reales. Es, en el fondo, una reflexi\u00f3n existencialista sobre el individuo y su papel en el universo, en la vida. \u00abEs ya una obra cl\u00e1sica\u00bb, concluye G\u00f3mez Cadenas.<\/p>\n<p>Esta <a href=\"http:\/\/www.valenciaplaza.com\/ver\/159171\/cronicas-marcianas-ray-bradbury.html\" target=\"_blank\">entrada<\/a> fue originalmente publicada por <a href=\"https:\/\/es.linkedin.com\/pub\/carlos-aimeur\/10\/24\/28\" target=\"_blank\">Carlos Aimeur<\/a> en <a href=\"http:\/\/www.valenciaplaza.com\/\" target=\"_blank\">Valencia Plaza<\/a>, el 26-6-2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minotauro reedita la colecci\u00f3n de relatos que convirti\u00f3 a Ray Bradbury en un autor de \u00e9xito y traspas\u00f3 los l\u00edmites del g\u00e9nero. \u00bfQu\u00e9 ha hecho este hombre de Illinois, me pregunto al cerrar las p\u00e1ginas de su libro, para que episodios de la conquista de otro planeta me llenen de terror y soledad? \u00bfC\u00f3mo pueden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-467","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-recensiones-criticas-y-analisis-de-publicaciones","post_format-post-format-gallery"],"jetpack_featured_media_url":"https:\/\/redfilosofia.es\/atheneblog\/wp-content\/uploads\/sites\/5\/2015\/06\/imagen192643m.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-7x","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":2,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/467\/revisions"}],"predecessor-version":[{"id":470,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/467\/revisions\/470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media\/468"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}