{"id":501,"date":"2015-07-15T11:55:06","date_gmt":"2015-07-15T11:55:06","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=501"},"modified":"2015-07-15T11:55:06","modified_gmt":"2015-07-15T11:55:06","slug":"los-ninos-que-discuten-sobre-conceptos-de-filosofia-mejoran-en-lectura-y-matematicas","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/07\/15\/los-ninos-que-discuten-sobre-conceptos-de-filosofia-mejoran-en-lectura-y-matematicas\/","title":{"rendered":"Los ni\u00f1os que discuten sobre conceptos de Filosof\u00eda mejoran en lectura y matem\u00e1ticas"},"content":{"rendered":"<p>\u00bfQu\u00e9 ventajas tiene que un ni\u00f1o de diez a\u00f1os mantenga discusiones filos\u00f3ficas acerca de conceptos como la verdad, la justicia o el conocimiento con sus compa\u00f1eros? M\u00e1s all\u00e1 de los beneficios que puede aportarle profundizar en conocimientos filos\u00f3ficos, cient\u00edficos de la Universidad de Durham han descubierto que tambi\u00e9n <strong>podr\u00eda ayudarles a mejorar sus habilidades en matem\u00e1ticas y lectura<\/strong>, lo que podr\u00eda suponer hasta un avance de dos meses en alumnos de entornos desfavorecidos.<\/p>\n<p>La investigaci\u00f3n, financiada por la Education Endowment Foundation (EEF), se desarroll\u00f3 con 3.159 alumnos de 48 escuelas en el Reino Unido, con los que se puso en pr\u00e1ctica el proyecto \u201cFilosof\u00eda para Ni\u00f1os\u201d, utilizado por unos 3.000 profesores en Reino Unido.<\/p>\n<p>Por los resultados se dedujo que los alumnos que los participaron en las sesiones filos\u00f3ficas tuvieron un avance de cuatro meses en el \u00e1rea relacionada con la lectura, y de tres meses en matem\u00e1ticas, al tiempo que tambi\u00e9n avanzaron un par de meses en la capacidad de escritura respecto a otros compa\u00f1eros que no realizaron las sesiones de filosof\u00eda. Adem\u00e1s, los profesores observaron que los ni\u00f1os que realizaban discusiones filos\u00f3ficas con sus iguales <strong>ganaron en confianza, paciencia y autoestima<\/strong>.<\/p>\n<p>El investigador que ha dirigido el proyecto, Stephen Gorard, profesor de la Facultad de Educaci\u00f3n de la Universidad de Durham, ha comentado al respecto que \u201clas sesiones de filosof\u00eda pueden tener un impacto positivo en matem\u00e1ticas, lectura o escritura, pero lo m\u00e1s importante es que <strong>parecen funcionar especialmente bien en ni\u00f1os m\u00e1s desfavorecidos<\/strong>. Esto es importante para identificar qu\u00e9 funciona y qu\u00e9 no, y ayudar a los directores a decidir c\u00f3mo gastar sus fondos para lograr el mayor beneficio de los alumnos\u201d.<\/p>\n<p>El programa \u201cFilosof\u00eda para Ni\u00f1os\u201d ayuda a los alumnos a cuestionar, razonar y construir argumentos, mientras que, para poder realizarlo, los profesores reciben dos d\u00edas de capacitaci\u00f3n profesional antes del programa, y un seguimiento a lo largo del mismo.<\/p>\n<p>En una lecci\u00f3n t\u00edpica, profesores y alumnos se sientan en un c\u00edrculo. El docente comienza presentando un est\u00edmulo, como un v\u00eddeo, una imagen o un peri\u00f3dico para provocar el inter\u00e9s de los alumnos. Despu\u00e9s, se invita a los ni\u00f1os a pensar en silencio y se divide a los ni\u00f1os en grupos, de manera que cada uno selecciona una pregunta con potencial filos\u00f3fico, de manera que se estimule una discusi\u00f3n con el resto. Estas discusiones son compatibles con actividades orientadas a <strong>desarrollar el razonamiento y la comprensi\u00f3n de conceptos<\/strong> en los ni\u00f1os.<\/p>\n<p>Por su parte, Kevan Collins, director ejecutivo de la EEF, ha confirmado que los resultados del programa \u201cnos dan evidencia de su impacto positivo en matem\u00e1ticas y lectura de los alumnos de Primaria. Dado su bajo costo, los profesores deben utilizar los resultados de la investigaci\u00f3n para plantearse seriamente si incluir estas sesiones de filosof\u00eda en sus aulas\u201d.<\/p>\n<blockquote><p>Esta noticia ha sido publicada originalmente por Eva del Amo en: www.aprendemas.com<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 ventajas tiene que un ni\u00f1o de diez a\u00f1os mantenga discusiones filos\u00f3ficas acerca de conceptos como la verdad, la justicia o el conocimiento con sus compa\u00f1eros? M\u00e1s all\u00e1 de los beneficios que puede aportarle profundizar en conocimientos filos\u00f3ficos, cient\u00edficos de la Universidad de Durham han descubierto que tambi\u00e9n podr\u00eda ayudarles a mejorar sus habilidades en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5,3],"tags":[12,15,110,46],"class_list":["post-501","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-articulos","category-noticias","tag-educacion","tag-filosofia","tag-ninos","tag-pensamiento-critico","post_format-post-format-gallery"],"jetpack_featured_media_url":"https:\/\/redfilosofia.es\/atheneblog\/wp-content\/uploads\/sites\/5\/2015\/07\/ni\u00f1ofilo.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-85","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":1,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":503,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/501\/revisions\/503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media\/502"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}