{"id":622,"date":"2015-10-10T11:14:58","date_gmt":"2015-10-10T11:14:58","guid":{"rendered":"https:\/\/redfilosofia.es\/atheneblog\/?p=622"},"modified":"2015-10-10T11:14:58","modified_gmt":"2015-10-10T11:14:58","slug":"las-comunidades-que-no-amaban-la-filosofia","status":"publish","type":"post","link":"https:\/\/redfilosofia.es\/atheneblog\/2015\/10\/10\/las-comunidades-que-no-amaban-la-filosofia\/","title":{"rendered":"Las Comunidades que no amaban la Filosof\u00eda"},"content":{"rendered":"<div id=\"NC\">\n<div class=\"n1 sin_borde dentroNoticia\">\n<blockquote>\n<div class=\"entradilla\">La Ley de Mejora de la Calidad de la Ense\u00f1anza (LOMCE) arrincona a la <strong>Filosof\u00eda<\/strong>en los insitutos, de los que los alumnos podr\u00e1n salir sin haber cursado ninguna materia relacionada. No obstante, hay comunidades que han adaptado la ley para que no pierda tanto peso, mientras que otras, como Madrid, adaptar\u00e1n la norma sin m\u00e1s. La Red Espa\u00f1ola de Filosof\u00eda (REF) se re\u00fane este mi\u00e9rcoles con el consejero madrile\u00f1os de Educaci\u00f3n, <strong>Rafael van Grieken<\/strong>, para pedir un mejor tratamiento a esta materia que contribuye a la formaci\u00f3n integral de los alumnos.<\/div>\n<\/blockquote>\n<div id=\"bloque_nadjuntos\">\n<h3 style=\"text-align: justify\">La Filosof\u00eda comenzar\u00e1 a desaparecer de los centros el pr\u00f3ximo curso, cuando la reforma educativa entre en vigor en el segundo a\u00f1o de los ciclos de Secundaria. As\u00ed que esta es la \u00faltima batalla para el colectivo, que lleva tres a\u00f1os luchando por no perder peso dentro de los institutos con el fin de que los alumnos puedan formar su esp\u00edritu cr\u00edtico. Con la LOMCE, desaparece \u00c9tica en 4\u00ba de la ESO, que era obligatoria, y Filosof\u00eda pasar\u00e1 a ser una optativa entre casi una decena de opciones. En 1\u00ba de Bachillerato, se mantiene Filosof\u00eda como obligatoria, pero se pierde en 2\u00ba, donde queda como optativa, en principio, solo en las opciones de Humanidad y Ciencias Sociales.<\/h3>\n<div class=\"content_adjunto\"><\/div>\n<\/div>\n<div class=\"texto\">\n<p style=\"text-align: justify\">En cualquier caso, hay comunidades donde se ha conseguido salvar la asignura, mientras que en otras se mantiene el texto de la LOMCE sin mejoras o incluso con m\u00e1s impedimentos. <strong>Cantabria \u00abes la Comunidad que mejor trata la Filosof\u00eda\u00bb<\/strong>, asegura Esperanza Rodr\u00edguez, responsable de la Comisi\u00f3n de Educaci\u00f3n de la Red Espa\u00f1ola de Filosof\u00eda, que ha elaborado un informe comparando las 17 realidad diferentes de esta asignatura. En concreto, su aportaci\u00f3n ha sido hacerla obligatoria para todas las modalidades de Bachillerato, menos Artes, donde era muy dif\u00edcil de encajar. \u00abCantabria se ha dado cuenta de que los alumnos van a tener que examinarse en la prueba final de Bachillerato, lo que llamamos rev\u00e1lida, todas las troncales. Pero todas tienen continuidad en 2\u00ba, menos Filosof\u00eda\u00bb, explica Rodr\u00edguez. De esta manera, los alumnos seguir\u00e1n teniendo contacto con la asignatura.<strong> Andaluc\u00eda tambi\u00e9n ha hecho obligatoria Historia de la Filosof\u00eda de 2\u00ba<\/strong> con una carga lectiva m\u00ednima de dos horas.<\/p>\n<p style=\"text-align: justify\">Otras comunidades han convertido la asignatura en obligatoria para Humanidades (<strong>Murcia<\/strong>) y otras tambi\u00e9n en Ciencias Sociales (<strong>La Rioja<\/strong>). Valencia la hecho optativa en todas las modalidades, pero se compromete a aceptar <strong>grupos de 7 alumnos<\/strong>, frente a los 15 alumnos o m\u00e1s que suelen ser necesarios<strong>. Galicia<\/strong>, por su parte, contin\u00faa con su tradici\u00f3n de ofertar optativas como Antropolog\u00eda, \u00c9tica y Filosof\u00eda del Derecho o Filosof\u00eda de la Ciencia.<\/p>\n<p style=\"text-align: justify\">Respecto a la asignatura de <strong>Filosof\u00eda de 4\u00ba de la ESO<\/strong>, que sustituye a \u00c9tica, obligatoria hasta este a\u00f1o, lo normal es que aparezca como optativa, pero hay comunidades, como el Pa\u00eds Vasco o Castilla y Le\u00f3n donde ni siquiera la incluyen, y otras que la convierten en obligatoria, como La Rioja o Extremadura.<\/p>\n<p style=\"text-align: justify\">En Madrid, la situaci\u00f3n es muy similar a la prevista por la LOMCE, pero desde la REF apuntan un defecto importante en su elaboraci\u00f3n, ya que el hecho de que la optativa de 2\u00ba de Bachillerato para Ciencias y Tecnolog\u00eda sea de cuatro horas har\u00e1 imposible a los alumnos cursarla, ya que compite con otras de dos. Para intentar mejorar la situaci\u00f3n de la Filosof\u00eda en Madrid y plantearle algunas situaciones, la REF se re\u00fane con el consejero de Educaci\u00f3n este mi\u00e9rcoles por la tarde.<\/p>\n<blockquote>\n<p style=\"text-align: justify\">Esta noticia ha sido escrita por Carmen M. Guti\u00e9rres y publicada en: www.madridiario.es<\/p>\n<p style=\"text-align: justify\">Fecha: mi\u00e9rcoles 07 de octubre de 2015.<\/p>\n<p style=\"text-align: justify\">Fotograf\u00eda: Diego S\u00e1nchez<\/p>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ley de Mejora de la Calidad de la Ense\u00f1anza (LOMCE) arrincona a la Filosof\u00edaen los insitutos, de los que los alumnos podr\u00e1n salir sin haber cursado ninguna materia relacionada. No obstante, hay comunidades que han adaptado la ley para que no pierda tanto peso, mientras que otras, como Madrid, adaptar\u00e1n la norma sin m\u00e1s. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[12,79],"class_list":["post-622","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-members","tag-educacion","tag-madrid","post_format-post-format-gallery"],"jetpack_featured_media_url":"https:\/\/redfilosofia.es\/atheneblog\/wp-content\/uploads\/sites\/5\/2015\/10\/filomadrid.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5OYFZ-a2","_links":{"self":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/comments?post=622"}],"version-history":[{"count":1,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/622\/revisions"}],"predecessor-version":[{"id":624,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/posts\/622\/revisions\/624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media\/623"}],"wp:attachment":[{"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/media?parent=622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/categories?post=622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redfilosofia.es\/atheneblog\/wp-json\/wp\/v2\/tags?post=622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}